{"id":1661,"date":"2016-03-08T04:21:10","date_gmt":"2016-03-08T04:21:10","guid":{"rendered":"https:\/\/www.aguarda.es\/?p=1661"},"modified":"2016-03-08T04:21:10","modified_gmt":"2016-03-08T04:21:10","slug":"a-policia-local-da-guarda-unese-a-campana-especial-sobre-o-cinturon-de-seguridade-e-sistemas-de-retencion-infantil-impulsada-pola-direccion-xeral-de-trafico","status":"publish","type":"post","link":"https:\/\/www.aguarda.es\/en\/a-policia-local-da-guarda-unese-a-campana-especial-sobre-o-cinturon-de-seguridade-e-sistemas-de-retencion-infantil-impulsada-pola-direccion-xeral-de-trafico\/","title":{"rendered":"A Polic\u00eda Local da Guarda \u00fanese a campa\u00f1a especial sobre o Cintur\u00f3n de Seguridade e Sistemas de Retenci\u00f3n Infantil impulsada pola Direcci\u00f3n Xeral de Tr\u00e1fico"},"content":{"rendered":"<p>Os axentes locais levar\u00e1n a cabo esta campa\u00f1a nas r\u00faas guardesas dende o luns 14 de marzo ata o domingo 20, ambos inclusive.<\/p>\n<p>  <!--more-->  <\/p>\n<p>\u00a0<\/p>\n<p>A Polic\u00eda Local da Guarda \u00fanese a \u201cCampa\u00f1a Especial sobre o Cintur\u00f3n de Seguridade e Sistemas de Retenci\u00f3n Infantil (SRI) impulsada pola Direcci\u00f3n Xeral de Tr\u00e1fico e o Ministerio do Interior.<\/p>\n<p>Os axentes locais levar\u00e1n a cabo esta campa\u00f1a nas r\u00faas guardesas dende o luns 14 de marzo ata o domingo 20, ambos inclusive.<\/p>\n<p>Ambos sistemas de seguridade son os m\u00e1is sinxelos, rendibles e eficaces. Estudos afirman que reduce \u00e1 metade o risco de morte en caso de accidente.<\/p>\n<p>Vixiar \u00e9 un dos m\u00e9todos m\u00e1is efectivos para incrementar e concienciar do seu uso por iso se levan a cabo campa\u00f1as especiais como a que se levar\u00e1 a cabo na pr\u00f3xima semana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os axentes locais levar\u00e1n a cabo esta campa\u00f1a nas r\u00faas guardesas dende o luns 14 de marzo ata o domingo 20, ambos inclusive.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[44],"tags":[],"class_list":["post-1661","post","type-post","status-publish","format-standard","hentry","category-policia-local"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Polic\u00eda Local da Guarda \u00fanese a campa\u00f1a especial sobre o Cintur\u00f3n de Seguridade e Sistemas de Retenci\u00f3n Infantil impulsada pola Direcci\u00f3n Xeral de Tr\u00e1fico - Concello da Guarda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aguarda.es\/en\/a-policia-local-da-guarda-unese-a-campana-especial-sobre-o-cinturon-de-seguridade-e-sistemas-de-retencion-infantil-impulsada-pola-direccion-xeral-de-trafico\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Polic\u00eda Local da Guarda \u00fanese a campa\u00f1a especial sobre o Cintur\u00f3n de Seguridade e Sistemas de Retenci\u00f3n Infantil impulsada pola Direcci\u00f3n Xeral de Tr\u00e1fico - Concello da Guarda\" \/>\n<meta property=\"og:description\" content=\"Os axentes locais levar\u00e1n a cabo esta campa\u00f1a nas r\u00faas guardesas dende o luns 14 de marzo ata o domingo 20, ambos inclusive.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aguarda.es\/en\/a-policia-local-da-guarda-unese-a-campana-especial-sobre-o-cinturon-de-seguridade-e-sistemas-de-retencion-infantil-impulsada-pola-direccion-xeral-de-trafico\/\" \/>\n<meta property=\"og:site_name\" content=\"Concello da Guarda\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ConcellodaGuarda\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-08T04:21:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aguarda.es\/wp-content\/uploads\/2017\/06\/escudo-full-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1135\" \/>\n\t<meta property=\"og:image:height\" content=\"712\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Concello\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AGuarda_es\" \/>\n<meta name=\"twitter:site\" content=\"@AGuarda_es\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Concello\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-policia-local-da-guarda-unese-a-campana-especial-sobre-o-cinturon-de-seguridade-e-sistemas-de-retencion-infantil-impulsada-pola-direccion-xeral-de-trafico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-policia-local-da-guarda-unese-a-campana-especial-sobre-o-cinturon-de-seguridade-e-sistemas-de-retencion-infantil-impulsada-pola-direccion-xeral-de-trafico\\\/\"},\"author\":{\"name\":\"Concello\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/ac30f4d74843174f0af56c730f74dd57\"},\"headline\":\"A Polic\u00eda Local da Guarda \u00fanese a campa\u00f1a especial sobre o Cintur\u00f3n de Seguridade e Sistemas de Retenci\u00f3n Infantil impulsada pola Direcci\u00f3n Xeral de Tr\u00e1fico\",\"datePublished\":\"2016-03-08T04:21:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-policia-local-da-guarda-unese-a-campana-especial-sobre-o-cinturon-de-seguridade-e-sistemas-de-retencion-infantil-impulsada-pola-direccion-xeral-de-trafico\\\/\"},\"wordCount\":176,\"commentCount\":0,\"articleSection\":[\"Polic\u00eda local\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-policia-local-da-guarda-unese-a-campana-especial-sobre-o-cinturon-de-seguridade-e-sistemas-de-retencion-infantil-impulsada-pola-direccion-xeral-de-trafico\\\/\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-policia-local-da-guarda-unese-a-campana-especial-sobre-o-cinturon-de-seguridade-e-sistemas-de-retencion-infantil-impulsada-pola-direccion-xeral-de-trafico\\\/\",\"name\":\"A Polic\u00eda Local da Guarda \u00fanese a campa\u00f1a especial sobre o Cintur\u00f3n de Seguridade e Sistemas de Retenci\u00f3n Infantil impulsada pola Direcci\u00f3n Xeral de Tr\u00e1fico - Concello da Guarda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#website\"},\"datePublished\":\"2016-03-08T04:21:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/ac30f4d74843174f0af56c730f74dd57\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-policia-local-da-guarda-unese-a-campana-especial-sobre-o-cinturon-de-seguridade-e-sistemas-de-retencion-infantil-impulsada-pola-direccion-xeral-de-trafico\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-policia-local-da-guarda-unese-a-campana-especial-sobre-o-cinturon-de-seguridade-e-sistemas-de-retencion-infantil-impulsada-pola-direccion-xeral-de-trafico\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-policia-local-da-guarda-unese-a-campana-especial-sobre-o-cinturon-de-seguridade-e-sistemas-de-retencion-infantil-impulsada-pola-direccion-xeral-de-trafico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Polic\u00eda Local da Guarda \u00fanese a campa\u00f1a especial sobre o Cintur\u00f3n de Seguridade e Sistemas de Retenci\u00f3n Infantil impulsada pola Direcci\u00f3n Xeral de Tr\u00e1fico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/\",\"name\":\"Concello da Guarda\",\"description\":\"P\u00e1xina web do concello da Guarda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/ac30f4d74843174f0af56c730f74dd57\",\"name\":\"Concello\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/604cbcd6d0c459552074918a50a795360692680b57347a8d1136bd96f9da962c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/604cbcd6d0c459552074918a50a795360692680b57347a8d1136bd96f9da962c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/604cbcd6d0c459552074918a50a795360692680b57347a8d1136bd96f9da962c?s=96&d=mm&r=g\",\"caption\":\"Concello\"},\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Polic\u00eda Local da Guarda \u00fanese a campa\u00f1a especial sobre o Cintur\u00f3n de Seguridade e Sistemas de Retenci\u00f3n Infantil impulsada pola Direcci\u00f3n Xeral de Tr\u00e1fico - Concello da Guarda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aguarda.es\/en\/a-policia-local-da-guarda-unese-a-campana-especial-sobre-o-cinturon-de-seguridade-e-sistemas-de-retencion-infantil-impulsada-pola-direccion-xeral-de-trafico\/","og_locale":"en_US","og_type":"article","og_title":"A Polic\u00eda Local da Guarda \u00fanese a campa\u00f1a especial sobre o Cintur\u00f3n de Seguridade e Sistemas de Retenci\u00f3n Infantil impulsada pola Direcci\u00f3n Xeral de Tr\u00e1fico - Concello da Guarda","og_description":"Os axentes locais levar\u00e1n a cabo esta campa\u00f1a nas r\u00faas guardesas dende o luns 14 de marzo ata o domingo 20, ambos inclusive.","og_url":"https:\/\/www.aguarda.es\/en\/a-policia-local-da-guarda-unese-a-campana-especial-sobre-o-cinturon-de-seguridade-e-sistemas-de-retencion-infantil-impulsada-pola-direccion-xeral-de-trafico\/","og_site_name":"Concello da Guarda","article_publisher":"https:\/\/www.facebook.com\/ConcellodaGuarda","article_published_time":"2016-03-08T04:21:10+00:00","og_image":[{"width":1135,"height":712,"url":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2017\/06\/escudo-full-2.jpg","type":"image\/jpeg"}],"author":"Concello","twitter_card":"summary_large_image","twitter_creator":"@AGuarda_es","twitter_site":"@AGuarda_es","twitter_misc":{"Written by":"Concello","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aguarda.es\/en\/a-policia-local-da-guarda-unese-a-campana-especial-sobre-o-cinturon-de-seguridade-e-sistemas-de-retencion-infantil-impulsada-pola-direccion-xeral-de-trafico\/#article","isPartOf":{"@id":"https:\/\/www.aguarda.es\/en\/a-policia-local-da-guarda-unese-a-campana-especial-sobre-o-cinturon-de-seguridade-e-sistemas-de-retencion-infantil-impulsada-pola-direccion-xeral-de-trafico\/"},"author":{"name":"Concello","@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/ac30f4d74843174f0af56c730f74dd57"},"headline":"A Polic\u00eda Local da Guarda \u00fanese a campa\u00f1a especial sobre o Cintur\u00f3n de Seguridade e Sistemas de Retenci\u00f3n Infantil impulsada pola Direcci\u00f3n Xeral de Tr\u00e1fico","datePublished":"2016-03-08T04:21:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aguarda.es\/en\/a-policia-local-da-guarda-unese-a-campana-especial-sobre-o-cinturon-de-seguridade-e-sistemas-de-retencion-infantil-impulsada-pola-direccion-xeral-de-trafico\/"},"wordCount":176,"commentCount":0,"articleSection":["Polic\u00eda local"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.aguarda.es\/en\/a-policia-local-da-guarda-unese-a-campana-especial-sobre-o-cinturon-de-seguridade-e-sistemas-de-retencion-infantil-impulsada-pola-direccion-xeral-de-trafico\/","url":"https:\/\/www.aguarda.es\/en\/a-policia-local-da-guarda-unese-a-campana-especial-sobre-o-cinturon-de-seguridade-e-sistemas-de-retencion-infantil-impulsada-pola-direccion-xeral-de-trafico\/","name":"A Polic\u00eda Local da Guarda \u00fanese a campa\u00f1a especial sobre o Cintur\u00f3n de Seguridade e Sistemas de Retenci\u00f3n Infantil impulsada pola Direcci\u00f3n Xeral de Tr\u00e1fico - Concello da Guarda","isPartOf":{"@id":"https:\/\/www.aguarda.es\/en\/#website"},"datePublished":"2016-03-08T04:21:10+00:00","author":{"@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/ac30f4d74843174f0af56c730f74dd57"},"breadcrumb":{"@id":"https:\/\/www.aguarda.es\/en\/a-policia-local-da-guarda-unese-a-campana-especial-sobre-o-cinturon-de-seguridade-e-sistemas-de-retencion-infantil-impulsada-pola-direccion-xeral-de-trafico\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aguarda.es\/en\/a-policia-local-da-guarda-unese-a-campana-especial-sobre-o-cinturon-de-seguridade-e-sistemas-de-retencion-infantil-impulsada-pola-direccion-xeral-de-trafico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aguarda.es\/en\/a-policia-local-da-guarda-unese-a-campana-especial-sobre-o-cinturon-de-seguridade-e-sistemas-de-retencion-infantil-impulsada-pola-direccion-xeral-de-trafico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.aguarda.es\/en\/"},{"@type":"ListItem","position":2,"name":"A Polic\u00eda Local da Guarda \u00fanese a campa\u00f1a especial sobre o Cintur\u00f3n de Seguridade e Sistemas de Retenci\u00f3n Infantil impulsada pola Direcci\u00f3n Xeral de Tr\u00e1fico"}]},{"@type":"WebSite","@id":"https:\/\/www.aguarda.es\/en\/#website","url":"https:\/\/www.aguarda.es\/en\/","name":"Concello da Guarda","description":"P\u00e1xina web do concello da Guarda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aguarda.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/ac30f4d74843174f0af56c730f74dd57","name":"Concello","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/604cbcd6d0c459552074918a50a795360692680b57347a8d1136bd96f9da962c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/604cbcd6d0c459552074918a50a795360692680b57347a8d1136bd96f9da962c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/604cbcd6d0c459552074918a50a795360692680b57347a8d1136bd96f9da962c?s=96&d=mm&r=g","caption":"Concello"},"url":"https:\/\/www.aguarda.es\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts\/1661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/comments?post=1661"}],"version-history":[{"count":0,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts\/1661\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/media?parent=1661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/categories?post=1661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/tags?post=1661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}