{"id":17491,"date":"2019-04-01T10:02:19","date_gmt":"2019-04-01T10:02:19","guid":{"rendered":"https:\/\/www.aguarda.es\/?p=17491"},"modified":"2019-04-01T10:02:19","modified_gmt":"2019-04-01T10:02:19","slug":"a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros","status":"publish","type":"post","link":"https:\/\/www.aguarda.es\/en\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\/","title":{"rendered":"A Guarda avanza na realizaci\u00f3n de cami\u00f1os escolares seguros"},"content":{"rendered":"<p style=\"text-align: justify\">A Guarda acolleu este xoves d\u00eda 28 de marzo de 2019 unha xuntanza para presentar o primeiro informe intermedio dos Cami\u00f1os Escolares Seguros na vila.<\/p>\n<p style=\"text-align: justify\">Nesta reuni\u00f3n estiveron presentes o Alcalde da Guarda, Antonio Lomba, a Concelleira de Educaci\u00f3n, Elena Baz, Mar\u00eda del Mar Gonz\u00e1lez, t\u00e9cnico da Deputaci\u00f3n de Pontevedra, M\u00aa Isabel de la Sant\u00edsima Trinidad, Directora do CEIP Manuel Rodr\u00edguez Sinde, Iris G\u00f3mez, Directora do CEIP As Solanas, Manuel \u00c1ngel Gonz\u00e1lez, Xefe da Polic\u00eda Local da Guarda e Alexandre Mouri\u00f1o, Arquitecto redactor do informe.<\/p>\n<p style=\"text-align: justify\">O Proxecto de Cami\u00f1os Escolares Seguros xurde ante a necesidade dun cambio de paradigma na maneira de moverse nas cidades e vilas, mellorando a seguridade vial establecendo rutas seguras ou \u00abSafeRoutestoSchool\u00bb, para que os nenos e nenas realicen os seus desprazamentos entre os seus fogares e os seus centros de ensino con total seguridade.<\/p>\n<p style=\"text-align: justify\">As ideas do pedagogo italiano Francesco Tonucci marcan un novo rumbo para os proxectos de cami\u00f1os escolares, cun novo concepto de cidade, propiciando a autonom\u00eda infantil.<\/p>\n<p style=\"text-align: justify\">Neste primeiro informe rec\u00f3llense varias actividades realizadas tendo como base a mobilidade do alumnado do CEIP Manuel Rodr\u00edguez Sinde, cun reco\u00f1ecemento do terreo, v\u00eddeo en time-lapse da chegada e sa\u00edda de alumnos, mapas e fotograf\u00edas das rutas empregadas para o acceso a este centro, as\u00ed coma un mapeamento dixital que se fixo cunha mostra de pais, grazas a unha aplicaci\u00f3n m\u00f3bil, que coa tecnolox\u00eda GPS axudou a facer os percorridos dixitais do alumnado, establecendo as rutas m\u00e1is empregadas.<\/p>\n<p style=\"text-align: justify\">Deste xeito logrouse establecer un croquis dun posible Cami\u00f1o Escolar Seguro de 730m de lonxitude nas r\u00faas Circunvalaci\u00f3n, Tui, Ourense, Enrique Mar\u00eda Sesto e Brasilino \u00c1lvarez.<\/p>\n<p style=\"text-align: justify\">O Proxecto continuar\u00e1 nos vindeiros meses con varias presentaci\u00f3ns destes resultados aos pais e nais, as\u00ed como aos alumnos, con enquisas e xornadas informativas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Guarda acolleu este xoves d\u00eda 28 de marzo de 2019 unha xuntanza para presentar o primeiro informe intermedio dos Cami\u00f1os Escolares Seguros na vila. Nesta reuni\u00f3n estiveron presentes o Alcalde da Guarda, Antonio Lomba, a Concelleira de Educaci\u00f3n, Elena &hellip; <\/p>\n","protected":false},"author":2,"featured_media":17492,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[33],"tags":[226,1771,1736,1772],"class_list":["post-17491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novas-xerais","tag-a-guarda","tag-caminos-escolares","tag-deputacion","tag-moilidade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Guarda avanza na realizaci\u00f3n de cami\u00f1os escolares seguros - Concello da Guarda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aguarda.es\/en\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Guarda avanza na realizaci\u00f3n de cami\u00f1os escolares seguros - Concello da Guarda\" \/>\n<meta property=\"og:description\" content=\"A Guarda acolleu este xoves d\u00eda 28 de marzo de 2019 unha xuntanza para presentar o primeiro informe intermedio dos Cami\u00f1os Escolares Seguros na vila. Nesta reuni\u00f3n estiveron presentes o Alcalde da Guarda, Antonio Lomba, a Concelleira de Educaci\u00f3n, Elena &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aguarda.es\/en\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\/\" \/>\n<meta property=\"og:site_name\" content=\"Concello da Guarda\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ConcellodaGuarda\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-01T10:02:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aguarda.es\/wp-content\/uploads\/2019\/04\/NP-29032019-A-Guarda-avanza-na-realizaci\u00f3n-de-cami\u00f1os-escolares-seguros-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"prensa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AGuarda_es\" \/>\n<meta name=\"twitter:site\" content=\"@AGuarda_es\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"prensa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\\\/\"},\"author\":{\"name\":\"prensa\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/c463ca3006858ffb349d11179d044f21\"},\"headline\":\"A Guarda avanza na realizaci\u00f3n de cami\u00f1os escolares seguros\",\"datePublished\":\"2019-04-01T10:02:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\\\/\"},\"wordCount\":334,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/NP-29032019-A-Guarda-avanza-na-realizaci\u00f3n-de-cami\u00f1os-escolares-seguros-1.jpg\",\"keywords\":[\"A Guarda\",\"cami\u00f1os escolares\",\"deputaci\u00f3n\",\"moilidade\"],\"articleSection\":[\"Xerais\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\\\/\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\\\/\",\"name\":\"A Guarda avanza na realizaci\u00f3n de cami\u00f1os escolares seguros - Concello da Guarda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/NP-29032019-A-Guarda-avanza-na-realizaci\u00f3n-de-cami\u00f1os-escolares-seguros-1.jpg\",\"datePublished\":\"2019-04-01T10:02:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/c463ca3006858ffb349d11179d044f21\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/NP-29032019-A-Guarda-avanza-na-realizaci\u00f3n-de-cami\u00f1os-escolares-seguros-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/NP-29032019-A-Guarda-avanza-na-realizaci\u00f3n-de-cami\u00f1os-escolares-seguros-1.jpg\",\"width\":800,\"height\":533,\"caption\":\"A Guarda acolleu este xoves d\u00eda 28 de marzo de 2019 unha xuntanza para presentar o primeiro informe intermedio dos Cami\u00f1os Escolares Seguros na vila.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Guarda avanza na realizaci\u00f3n de cami\u00f1os escolares seguros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/\",\"name\":\"Concello da Guarda\",\"description\":\"P\u00e1xina web do concello da Guarda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/c463ca3006858ffb349d11179d044f21\",\"name\":\"prensa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g\",\"caption\":\"prensa\"},\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/author\\\/prensa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Guarda avanza na realizaci\u00f3n de cami\u00f1os escolares seguros - Concello da Guarda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aguarda.es\/en\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\/","og_locale":"en_US","og_type":"article","og_title":"A Guarda avanza na realizaci\u00f3n de cami\u00f1os escolares seguros - Concello da Guarda","og_description":"A Guarda acolleu este xoves d\u00eda 28 de marzo de 2019 unha xuntanza para presentar o primeiro informe intermedio dos Cami\u00f1os Escolares Seguros na vila. Nesta reuni\u00f3n estiveron presentes o Alcalde da Guarda, Antonio Lomba, a Concelleira de Educaci\u00f3n, Elena &hellip;","og_url":"https:\/\/www.aguarda.es\/en\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\/","og_site_name":"Concello da Guarda","article_publisher":"https:\/\/www.facebook.com\/ConcellodaGuarda","article_published_time":"2019-04-01T10:02:19+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2019\/04\/NP-29032019-A-Guarda-avanza-na-realizaci\u00f3n-de-cami\u00f1os-escolares-seguros-1.jpg","type":"image\/jpeg"}],"author":"prensa","twitter_card":"summary_large_image","twitter_creator":"@AGuarda_es","twitter_site":"@AGuarda_es","twitter_misc":{"Written by":"prensa","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aguarda.es\/en\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\/#article","isPartOf":{"@id":"https:\/\/www.aguarda.es\/en\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\/"},"author":{"name":"prensa","@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/c463ca3006858ffb349d11179d044f21"},"headline":"A Guarda avanza na realizaci\u00f3n de cami\u00f1os escolares seguros","datePublished":"2019-04-01T10:02:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aguarda.es\/en\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\/"},"wordCount":334,"commentCount":0,"image":{"@id":"https:\/\/www.aguarda.es\/en\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2019\/04\/NP-29032019-A-Guarda-avanza-na-realizaci\u00f3n-de-cami\u00f1os-escolares-seguros-1.jpg","keywords":["A Guarda","cami\u00f1os escolares","deputaci\u00f3n","moilidade"],"articleSection":["Xerais"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.aguarda.es\/en\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\/","url":"https:\/\/www.aguarda.es\/en\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\/","name":"A Guarda avanza na realizaci\u00f3n de cami\u00f1os escolares seguros - Concello da Guarda","isPartOf":{"@id":"https:\/\/www.aguarda.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aguarda.es\/en\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\/#primaryimage"},"image":{"@id":"https:\/\/www.aguarda.es\/en\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2019\/04\/NP-29032019-A-Guarda-avanza-na-realizaci\u00f3n-de-cami\u00f1os-escolares-seguros-1.jpg","datePublished":"2019-04-01T10:02:19+00:00","author":{"@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/c463ca3006858ffb349d11179d044f21"},"breadcrumb":{"@id":"https:\/\/www.aguarda.es\/en\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aguarda.es\/en\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.aguarda.es\/en\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\/#primaryimage","url":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2019\/04\/NP-29032019-A-Guarda-avanza-na-realizaci\u00f3n-de-cami\u00f1os-escolares-seguros-1.jpg","contentUrl":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2019\/04\/NP-29032019-A-Guarda-avanza-na-realizaci\u00f3n-de-cami\u00f1os-escolares-seguros-1.jpg","width":800,"height":533,"caption":"A Guarda acolleu este xoves d\u00eda 28 de marzo de 2019 unha xuntanza para presentar o primeiro informe intermedio dos Cami\u00f1os Escolares Seguros na vila."},{"@type":"BreadcrumbList","@id":"https:\/\/www.aguarda.es\/en\/a-guarda-avanza-na-realizacion-de-caminos-escolares-seguros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.aguarda.es\/en\/"},{"@type":"ListItem","position":2,"name":"A Guarda avanza na realizaci\u00f3n de cami\u00f1os escolares seguros"}]},{"@type":"WebSite","@id":"https:\/\/www.aguarda.es\/en\/#website","url":"https:\/\/www.aguarda.es\/en\/","name":"Concello da Guarda","description":"P\u00e1xina web do concello da Guarda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aguarda.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/c463ca3006858ffb349d11179d044f21","name":"prensa","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g","caption":"prensa"},"url":"https:\/\/www.aguarda.es\/en\/author\/prensa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts\/17491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/comments?post=17491"}],"version-history":[{"count":1,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts\/17491\/revisions"}],"predecessor-version":[{"id":17494,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts\/17491\/revisions\/17494"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/media\/17492"}],"wp:attachment":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/media?parent=17491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/categories?post=17491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/tags?post=17491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}