{"id":18877,"date":"2019-07-15T15:28:26","date_gmt":"2019-07-15T15:28:26","guid":{"rendered":"https:\/\/www.aguarda.es\/?p=18877"},"modified":"2019-07-15T15:28:26","modified_gmt":"2019-07-15T15:28:26","slug":"gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda","status":"publish","type":"post","link":"https:\/\/www.aguarda.es\/en\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\/","title":{"rendered":"Gran recollida de pl\u00e1sticos este domingo na costa da Guarda"},"content":{"rendered":"<p style=\"text-align: justify\">O vindeiro domingo d\u00eda 21 de xullo a Agrupaci\u00f3n Guardesa de Pescadores, Mari\u00f1eiros e Mariscadores non profesionais &#8220;O Buxeiro&#8221; organiza unha gran recollida de pl\u00e1sticos na costa da Guarda.<\/p>\n<p style=\"text-align: justify\">Esta actividade, que contar\u00e1 coa colaboraci\u00f3n da Conceller\u00eda de Medio Ambiente do Concello da Guarda, realizarase por diferentes puntos da costa guardesa, tentando eliminar aqueles restos de pl\u00e1sticos que se atopen pola costa.<\/p>\n<p style=\"text-align: justify\">O punto de reuni\u00f3n ser\u00e1 a Alameda da Guarda \u00e1s 8:00h da ma\u00f1\u00e1, onde se repartir\u00e1n guantes e bolsas e se explicar\u00e1 como ser\u00e1 o funcionamento desta actividade, para a que non \u00e9 preciso inscrici\u00f3n previa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O vindeiro domingo d\u00eda 21 de xullo a Agrupaci\u00f3n Guardesa de Pescadores, Mari\u00f1eiros e Mariscadores non profesionais &#8220;O Buxeiro&#8221; organiza unha gran recollida de pl\u00e1sticos na costa da Guarda. Esta actividade, que contar\u00e1 coa colaboraci\u00f3n da Conceller\u00eda de Medio Ambiente &hellip; <\/p>\n","protected":false},"author":2,"featured_media":18878,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[40],"tags":[226,227],"class_list":["post-18877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medio-ambiente","tag-a-guarda","tag-medio-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gran recollida de pl\u00e1sticos este domingo na costa da Guarda - Concello da Guarda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aguarda.es\/en\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gran recollida de pl\u00e1sticos este domingo na costa da Guarda - Concello da Guarda\" \/>\n<meta property=\"og:description\" content=\"O vindeiro domingo d\u00eda 21 de xullo a Agrupaci\u00f3n Guardesa de Pescadores, Mari\u00f1eiros e Mariscadores non profesionais &#8220;O Buxeiro&#8221; organiza unha gran recollida de pl\u00e1sticos na costa da Guarda. Esta actividade, que contar\u00e1 coa colaboraci\u00f3n da Conceller\u00eda de Medio Ambiente &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aguarda.es\/en\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\/\" \/>\n<meta property=\"og:site_name\" content=\"Concello da Guarda\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ConcellodaGuarda\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-15T15:28:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aguarda.es\/wp-content\/uploads\/2019\/07\/Sin-t\u00edtulo-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"prensa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AGuarda_es\" \/>\n<meta name=\"twitter:site\" content=\"@AGuarda_es\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"prensa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\\\/\"},\"author\":{\"name\":\"prensa\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/c463ca3006858ffb349d11179d044f21\"},\"headline\":\"Gran recollida de pl\u00e1sticos este domingo na costa da Guarda\",\"datePublished\":\"2019-07-15T15:28:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\\\/\"},\"wordCount\":117,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Sin-t\u00edtulo-3.jpg\",\"keywords\":[\"A Guarda\",\"Medio ambiente\"],\"articleSection\":[\"Medio ambiente\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\\\/\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\\\/\",\"name\":\"Gran recollida de pl\u00e1sticos este domingo na costa da Guarda - Concello da Guarda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Sin-t\u00edtulo-3.jpg\",\"datePublished\":\"2019-07-15T15:28:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/c463ca3006858ffb349d11179d044f21\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aguarda.es\\\/en\\\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Sin-t\u00edtulo-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Sin-t\u00edtulo-3.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gran recollida de pl\u00e1sticos este domingo na costa da Guarda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/\",\"name\":\"Concello da Guarda\",\"description\":\"P\u00e1xina web do concello da Guarda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/c463ca3006858ffb349d11179d044f21\",\"name\":\"prensa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g\",\"caption\":\"prensa\"},\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/author\\\/prensa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gran recollida de pl\u00e1sticos este domingo na costa da Guarda - Concello da Guarda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aguarda.es\/en\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\/","og_locale":"en_US","og_type":"article","og_title":"Gran recollida de pl\u00e1sticos este domingo na costa da Guarda - Concello da Guarda","og_description":"O vindeiro domingo d\u00eda 21 de xullo a Agrupaci\u00f3n Guardesa de Pescadores, Mari\u00f1eiros e Mariscadores non profesionais &#8220;O Buxeiro&#8221; organiza unha gran recollida de pl\u00e1sticos na costa da Guarda. Esta actividade, que contar\u00e1 coa colaboraci\u00f3n da Conceller\u00eda de Medio Ambiente &hellip;","og_url":"https:\/\/www.aguarda.es\/en\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\/","og_site_name":"Concello da Guarda","article_publisher":"https:\/\/www.facebook.com\/ConcellodaGuarda","article_published_time":"2019-07-15T15:28:26+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2019\/07\/Sin-t\u00edtulo-3.jpg","type":"image\/jpeg"}],"author":"prensa","twitter_card":"summary_large_image","twitter_creator":"@AGuarda_es","twitter_site":"@AGuarda_es","twitter_misc":{"Written by":"prensa","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aguarda.es\/en\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\/#article","isPartOf":{"@id":"https:\/\/www.aguarda.es\/en\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\/"},"author":{"name":"prensa","@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/c463ca3006858ffb349d11179d044f21"},"headline":"Gran recollida de pl\u00e1sticos este domingo na costa da Guarda","datePublished":"2019-07-15T15:28:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aguarda.es\/en\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\/"},"wordCount":117,"commentCount":0,"image":{"@id":"https:\/\/www.aguarda.es\/en\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2019\/07\/Sin-t\u00edtulo-3.jpg","keywords":["A Guarda","Medio ambiente"],"articleSection":["Medio ambiente"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.aguarda.es\/en\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\/","url":"https:\/\/www.aguarda.es\/en\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\/","name":"Gran recollida de pl\u00e1sticos este domingo na costa da Guarda - Concello da Guarda","isPartOf":{"@id":"https:\/\/www.aguarda.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aguarda.es\/en\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\/#primaryimage"},"image":{"@id":"https:\/\/www.aguarda.es\/en\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2019\/07\/Sin-t\u00edtulo-3.jpg","datePublished":"2019-07-15T15:28:26+00:00","author":{"@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/c463ca3006858ffb349d11179d044f21"},"breadcrumb":{"@id":"https:\/\/www.aguarda.es\/en\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aguarda.es\/en\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.aguarda.es\/en\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\/#primaryimage","url":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2019\/07\/Sin-t\u00edtulo-3.jpg","contentUrl":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2019\/07\/Sin-t\u00edtulo-3.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.aguarda.es\/en\/gran-recollida-de-plasticos-este-domingo-na-costa-da-guarda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.aguarda.es\/en\/"},{"@type":"ListItem","position":2,"name":"Gran recollida de pl\u00e1sticos este domingo na costa da Guarda"}]},{"@type":"WebSite","@id":"https:\/\/www.aguarda.es\/en\/#website","url":"https:\/\/www.aguarda.es\/en\/","name":"Concello da Guarda","description":"P\u00e1xina web do concello da Guarda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aguarda.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/c463ca3006858ffb349d11179d044f21","name":"prensa","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g","caption":"prensa"},"url":"https:\/\/www.aguarda.es\/en\/author\/prensa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts\/18877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/comments?post=18877"}],"version-history":[{"count":1,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts\/18877\/revisions"}],"predecessor-version":[{"id":18880,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts\/18877\/revisions\/18880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/media\/18878"}],"wp:attachment":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/media?parent=18877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/categories?post=18877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/tags?post=18877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}