{"id":19047,"date":"2019-07-29T09:45:33","date_gmt":"2019-07-29T09:45:33","guid":{"rendered":"https:\/\/www.aguarda.es\/?p=19047"},"modified":"2019-07-29T09:45:33","modified_gmt":"2019-07-29T09:45:33","slug":"entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume","status":"publish","type":"post","link":"https:\/\/www.aguarda.es\/en\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\/","title":{"rendered":"Entrega do diploma de ouro da Rede galega de praias sen fume"},"content":{"rendered":"<p style=\"text-align: justify\">O pasado m\u00e9rcores d\u00eda 24 de xullo o Director Xeral de Sa\u00fade P\u00fablica, Andr\u00e9s Paz-Ares Rodr\u00edguez, entregoulle ao concelleiro de Tr\u00e1fico e emerxencias, e medio ambiente, Xan Lois Lomba, o diploma de ouro da Rede galega de praias se fume, asistiron tam\u00e9n o tenente-alcalde, Anxo Baz e a concelleira Montserrat Magallanes.<\/p>\n<p style=\"text-align: justify\">Nestes momentos, 141 praias de 64 concellos integran a rede, sendo A Guarda un dos 10 municipios no que todas as s\u00faas praias se atopan dentro da rede.<\/p>\n<p style=\"text-align: justify\">A Rede, posta en marcha pola Conseller\u00eda de Sanidade, a trav\u00e9s da s\u00faa Direcci\u00f3n Xeral de Sa\u00fade P\u00fablica, \u00e9 cada vez m\u00e1is extensa, repartida non s\u00f3 nos concellos da costa, sen\u00f3n, tam\u00e9n, polas ribeiras dos r\u00edos, xa que conta con 29 praias fluviais, o que facilita poder elixir espazos libres de fume do tabaco para desfrutar do tempo de ocio.<\/p>\n<p style=\"text-align: justify\">Dende o Concello da Guarda rec\u00f3rdase que \u00e9 moi necesaria a implicaci\u00f3n de todos e a participaci\u00f3n activa da sociedade para sensibilizar \u00e1 poboaci\u00f3n ante estes consumos de risco para a sa\u00fade.<\/p>\n<p style=\"text-align: justify\">As \u00faltimas cifras de prevalencia en Galicia indican que o 19,7% da poboaci\u00f3n da nosa comunidade \u00e9 fumadora e o 15,3% dos mozos e mozas de 16 a 24 anos fuman diariamente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O pasado m\u00e9rcores d\u00eda 24 de xullo o Director Xeral de Sa\u00fade P\u00fablica, Andr\u00e9s Paz-Ares Rodr\u00edguez, entregoulle ao concelleiro de Tr\u00e1fico e emerxencias, e medio ambiente, Xan Lois Lomba, o diploma de ouro da Rede galega de praias se fume, &hellip; <\/p>\n","protected":false},"author":2,"featured_media":19048,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[40,56,33],"tags":[226,227,229,1901,1618],"class_list":["post-19047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medio-ambiente","category-turismo","category-novas-xerais","tag-a-guarda","tag-medio-ambiente","tag-praias","tag-praias-sen-fume","tag-sanidade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entrega do diploma de ouro da Rede galega de praias sen fume - Concello da Guarda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aguarda.es\/en\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrega do diploma de ouro da Rede galega de praias sen fume - Concello da Guarda\" \/>\n<meta property=\"og:description\" content=\"O pasado m\u00e9rcores d\u00eda 24 de xullo o Director Xeral de Sa\u00fade P\u00fablica, Andr\u00e9s Paz-Ares Rodr\u00edguez, entregoulle ao concelleiro de Tr\u00e1fico e emerxencias, e medio ambiente, Xan Lois Lomba, o diploma de ouro da Rede galega de praias se fume, &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aguarda.es\/en\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\/\" \/>\n<meta property=\"og:site_name\" content=\"Concello da Guarda\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ConcellodaGuarda\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-29T09:45:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aguarda.es\/wp-content\/uploads\/2019\/07\/NP-29072019-Entrega-do-diploma-de-ouro-da-Rede-galega-de-praias-sen-fume-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"prensa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AGuarda_es\" \/>\n<meta name=\"twitter:site\" content=\"@AGuarda_es\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"prensa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\\\/\"},\"author\":{\"name\":\"prensa\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/c463ca3006858ffb349d11179d044f21\"},\"headline\":\"Entrega do diploma de ouro da Rede galega de praias sen fume\",\"datePublished\":\"2019-07-29T09:45:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\\\/\"},\"wordCount\":227,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/NP-29072019-Entrega-do-diploma-de-ouro-da-Rede-galega-de-praias-sen-fume-3.jpg\",\"keywords\":[\"A Guarda\",\"Medio ambiente\",\"praias\",\"praias sen fume\",\"sanidade\"],\"articleSection\":[\"Medio ambiente\",\"Turismo\",\"Xerais\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\\\/\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\\\/\",\"name\":\"Entrega do diploma de ouro da Rede galega de praias sen fume - Concello da Guarda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/NP-29072019-Entrega-do-diploma-de-ouro-da-Rede-galega-de-praias-sen-fume-3.jpg\",\"datePublished\":\"2019-07-29T09:45:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/c463ca3006858ffb349d11179d044f21\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aguarda.es\\\/en\\\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/NP-29072019-Entrega-do-diploma-de-ouro-da-Rede-galega-de-praias-sen-fume-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/NP-29072019-Entrega-do-diploma-de-ouro-da-Rede-galega-de-praias-sen-fume-3.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entrega do diploma de ouro da Rede galega de praias sen fume\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/\",\"name\":\"Concello da Guarda\",\"description\":\"P\u00e1xina web do concello da Guarda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/c463ca3006858ffb349d11179d044f21\",\"name\":\"prensa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g\",\"caption\":\"prensa\"},\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/author\\\/prensa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrega do diploma de ouro da Rede galega de praias sen fume - Concello da Guarda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aguarda.es\/en\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\/","og_locale":"en_US","og_type":"article","og_title":"Entrega do diploma de ouro da Rede galega de praias sen fume - Concello da Guarda","og_description":"O pasado m\u00e9rcores d\u00eda 24 de xullo o Director Xeral de Sa\u00fade P\u00fablica, Andr\u00e9s Paz-Ares Rodr\u00edguez, entregoulle ao concelleiro de Tr\u00e1fico e emerxencias, e medio ambiente, Xan Lois Lomba, o diploma de ouro da Rede galega de praias se fume, &hellip;","og_url":"https:\/\/www.aguarda.es\/en\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\/","og_site_name":"Concello da Guarda","article_publisher":"https:\/\/www.facebook.com\/ConcellodaGuarda","article_published_time":"2019-07-29T09:45:33+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2019\/07\/NP-29072019-Entrega-do-diploma-de-ouro-da-Rede-galega-de-praias-sen-fume-3.jpg","type":"image\/jpeg"}],"author":"prensa","twitter_card":"summary_large_image","twitter_creator":"@AGuarda_es","twitter_site":"@AGuarda_es","twitter_misc":{"Written by":"prensa","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aguarda.es\/en\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\/#article","isPartOf":{"@id":"https:\/\/www.aguarda.es\/en\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\/"},"author":{"name":"prensa","@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/c463ca3006858ffb349d11179d044f21"},"headline":"Entrega do diploma de ouro da Rede galega de praias sen fume","datePublished":"2019-07-29T09:45:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aguarda.es\/en\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\/"},"wordCount":227,"commentCount":0,"image":{"@id":"https:\/\/www.aguarda.es\/en\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2019\/07\/NP-29072019-Entrega-do-diploma-de-ouro-da-Rede-galega-de-praias-sen-fume-3.jpg","keywords":["A Guarda","Medio ambiente","praias","praias sen fume","sanidade"],"articleSection":["Medio ambiente","Turismo","Xerais"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.aguarda.es\/en\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\/","url":"https:\/\/www.aguarda.es\/en\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\/","name":"Entrega do diploma de ouro da Rede galega de praias sen fume - Concello da Guarda","isPartOf":{"@id":"https:\/\/www.aguarda.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aguarda.es\/en\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\/#primaryimage"},"image":{"@id":"https:\/\/www.aguarda.es\/en\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2019\/07\/NP-29072019-Entrega-do-diploma-de-ouro-da-Rede-galega-de-praias-sen-fume-3.jpg","datePublished":"2019-07-29T09:45:33+00:00","author":{"@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/c463ca3006858ffb349d11179d044f21"},"breadcrumb":{"@id":"https:\/\/www.aguarda.es\/en\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aguarda.es\/en\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.aguarda.es\/en\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\/#primaryimage","url":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2019\/07\/NP-29072019-Entrega-do-diploma-de-ouro-da-Rede-galega-de-praias-sen-fume-3.jpg","contentUrl":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2019\/07\/NP-29072019-Entrega-do-diploma-de-ouro-da-Rede-galega-de-praias-sen-fume-3.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.aguarda.es\/en\/entrega-do-diploma-de-ouro-da-rede-galega-de-praias-sen-fume\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.aguarda.es\/en\/"},{"@type":"ListItem","position":2,"name":"Entrega do diploma de ouro da Rede galega de praias sen fume"}]},{"@type":"WebSite","@id":"https:\/\/www.aguarda.es\/en\/#website","url":"https:\/\/www.aguarda.es\/en\/","name":"Concello da Guarda","description":"P\u00e1xina web do concello da Guarda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aguarda.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/c463ca3006858ffb349d11179d044f21","name":"prensa","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g","caption":"prensa"},"url":"https:\/\/www.aguarda.es\/en\/author\/prensa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts\/19047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/comments?post=19047"}],"version-history":[{"count":1,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts\/19047\/revisions"}],"predecessor-version":[{"id":19050,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts\/19047\/revisions\/19050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/media\/19048"}],"wp:attachment":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/media?parent=19047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/categories?post=19047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/tags?post=19047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}