{"id":1990,"date":"2016-07-01T09:08:08","date_gmt":"2016-07-01T09:08:08","guid":{"rendered":"https:\/\/www.aguarda.es\/?p=1990"},"modified":"2016-07-01T09:08:08","modified_gmt":"2016-07-01T09:08:08","slug":"a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran","status":"publish","type":"post","link":"https:\/\/www.aguarda.es\/en\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\/","title":{"rendered":"A Guarda incorpora dous Auxiliares de Polic\u00eda Local para a campa\u00f1a de ver\u00e1n"},"content":{"rendered":"<p lang=\"gl-ES\"><span>O alcalde da Guarda, Antonio Lomba Baz, deu a benvida este venres d\u00eda 1 de xullo pola ma\u00f1\u00e1 \u00f3s dous auxiliares de Polic\u00eda Local que foron incorporados \u00e1 plantilla da Polic\u00eda Local da vila ese mesmo d\u00eda.<\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p lang=\"gl-ES\"><span><span>O alcalde da Guarda, Antonio Lomba Baz, deu a benvida este venres d\u00eda 1 de xullo pola ma\u00f1\u00e1 \u00f3s dous auxiliares de Polic\u00eda Local que foron incorporados \u00e1 plantilla da Polic\u00eda Local da vila ese mesmo d\u00eda.<\/span><\/span><\/p>\n<p lang=\"gl-ES\"><span>\u00a0<\/span><\/p>\n<p lang=\"gl-ES\"><span>Os novos auxiliares, ambos naturais da Guarda, chegan tras prepararse para acadar o Certificado de Auxiliar de Polic\u00eda Local e facer un exame.<\/span><\/p>\n<p lang=\"gl-ES\"><span>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-1989\" src=\"https:\/\/www.aguarda.es\/wp-content\/uploads\/2016\/07\/2016_Polica%20local%201.JPG\" alt=\"\" width=\"581\" height=\"435\" \/><\/span><\/p>\n<p lang=\"gl-ES\"><span>Esta incorporaci\u00f3n busca axudar e reforzar a campa\u00f1a de ver\u00e1n, na que o traballo aumenta coa \u00e9poca das festa tradicionais populares e cunha maior actividade \u00f3 aire libre. Os auxiliares estar\u00e1n dende este mes de xullo ata o final do ano, no mes de decembro.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O alcalde da Guarda, Antonio Lomba Baz, deu a benvida este venres d\u00eda 1 de xullo pola ma\u00f1\u00e1 \u00f3s dous auxiliares de Polic\u00eda Local que foron incorporados \u00e1 plantilla da Polic\u00eda Local da vila ese mesmo d\u00eda.<\/p>\n","protected":false},"author":1,"featured_media":1989,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[33],"tags":[],"class_list":["post-1990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novas-xerais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Guarda incorpora dous Auxiliares de Polic\u00eda Local para a campa\u00f1a de ver\u00e1n - Concello da Guarda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aguarda.es\/en\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Guarda incorpora dous Auxiliares de Polic\u00eda Local para a campa\u00f1a de ver\u00e1n - Concello da Guarda\" \/>\n<meta property=\"og:description\" content=\"O alcalde da Guarda, Antonio Lomba Baz, deu a benvida este venres d\u00eda 1 de xullo pola ma\u00f1\u00e1 \u00f3s dous auxiliares de Polic\u00eda Local que foron incorporados \u00e1 plantilla da Polic\u00eda Local da vila ese mesmo d\u00eda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aguarda.es\/en\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\/\" \/>\n<meta property=\"og:site_name\" content=\"Concello da Guarda\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ConcellodaGuarda\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-01T09:08:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aguarda.es\/wp-content\/uploads\/2016\/07\/2016_Polica%20local%201.JPG\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Concello\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AGuarda_es\" \/>\n<meta name=\"twitter:site\" content=\"@AGuarda_es\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Concello\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\\\/\"},\"author\":{\"name\":\"Concello\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/ac30f4d74843174f0af56c730f74dd57\"},\"headline\":\"A Guarda incorpora dous Auxiliares de Polic\u00eda Local para a campa\u00f1a de ver\u00e1n\",\"datePublished\":\"2016-07-01T09:08:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\\\/\"},\"wordCount\":166,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/2016_Polica local 1.JPG\",\"articleSection\":[\"Xerais\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\\\/\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\\\/\",\"name\":\"A Guarda incorpora dous Auxiliares de Polic\u00eda Local para a campa\u00f1a de ver\u00e1n - Concello da Guarda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/2016_Polica local 1.JPG\",\"datePublished\":\"2016-07-01T09:08:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/ac30f4d74843174f0af56c730f74dd57\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/2016_Polica local 1.JPG\",\"contentUrl\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/2016_Polica local 1.JPG\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Guarda incorpora dous Auxiliares de Polic\u00eda Local para a campa\u00f1a de ver\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/\",\"name\":\"Concello da Guarda\",\"description\":\"P\u00e1xina web do concello da Guarda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/ac30f4d74843174f0af56c730f74dd57\",\"name\":\"Concello\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/604cbcd6d0c459552074918a50a795360692680b57347a8d1136bd96f9da962c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/604cbcd6d0c459552074918a50a795360692680b57347a8d1136bd96f9da962c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/604cbcd6d0c459552074918a50a795360692680b57347a8d1136bd96f9da962c?s=96&d=mm&r=g\",\"caption\":\"Concello\"},\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Guarda incorpora dous Auxiliares de Polic\u00eda Local para a campa\u00f1a de ver\u00e1n - Concello da Guarda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aguarda.es\/en\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\/","og_locale":"en_US","og_type":"article","og_title":"A Guarda incorpora dous Auxiliares de Polic\u00eda Local para a campa\u00f1a de ver\u00e1n - Concello da Guarda","og_description":"O alcalde da Guarda, Antonio Lomba Baz, deu a benvida este venres d\u00eda 1 de xullo pola ma\u00f1\u00e1 \u00f3s dous auxiliares de Polic\u00eda Local que foron incorporados \u00e1 plantilla da Polic\u00eda Local da vila ese mesmo d\u00eda.","og_url":"https:\/\/www.aguarda.es\/en\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\/","og_site_name":"Concello da Guarda","article_publisher":"https:\/\/www.facebook.com\/ConcellodaGuarda","article_published_time":"2016-07-01T09:08:08+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2016\/07\/2016_Polica local 1.JPG","type":"image\/jpeg"}],"author":"Concello","twitter_card":"summary_large_image","twitter_creator":"@AGuarda_es","twitter_site":"@AGuarda_es","twitter_misc":{"Written by":"Concello","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aguarda.es\/en\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\/#article","isPartOf":{"@id":"https:\/\/www.aguarda.es\/en\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\/"},"author":{"name":"Concello","@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/ac30f4d74843174f0af56c730f74dd57"},"headline":"A Guarda incorpora dous Auxiliares de Polic\u00eda Local para a campa\u00f1a de ver\u00e1n","datePublished":"2016-07-01T09:08:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aguarda.es\/en\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\/"},"wordCount":166,"commentCount":0,"image":{"@id":"https:\/\/www.aguarda.es\/en\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2016\/07\/2016_Polica local 1.JPG","articleSection":["Xerais"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.aguarda.es\/en\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\/","url":"https:\/\/www.aguarda.es\/en\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\/","name":"A Guarda incorpora dous Auxiliares de Polic\u00eda Local para a campa\u00f1a de ver\u00e1n - Concello da Guarda","isPartOf":{"@id":"https:\/\/www.aguarda.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aguarda.es\/en\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\/#primaryimage"},"image":{"@id":"https:\/\/www.aguarda.es\/en\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2016\/07\/2016_Polica local 1.JPG","datePublished":"2016-07-01T09:08:08+00:00","author":{"@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/ac30f4d74843174f0af56c730f74dd57"},"breadcrumb":{"@id":"https:\/\/www.aguarda.es\/en\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aguarda.es\/en\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.aguarda.es\/en\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\/#primaryimage","url":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2016\/07\/2016_Polica local 1.JPG","contentUrl":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2016\/07\/2016_Polica local 1.JPG","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.aguarda.es\/en\/a-guarda-incorpora-dous-auxiliares-de-policia-local-para-a-campana-de-veran\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.aguarda.es\/en\/"},{"@type":"ListItem","position":2,"name":"A Guarda incorpora dous Auxiliares de Polic\u00eda Local para a campa\u00f1a de ver\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/www.aguarda.es\/en\/#website","url":"https:\/\/www.aguarda.es\/en\/","name":"Concello da Guarda","description":"P\u00e1xina web do concello da Guarda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aguarda.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/ac30f4d74843174f0af56c730f74dd57","name":"Concello","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/604cbcd6d0c459552074918a50a795360692680b57347a8d1136bd96f9da962c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/604cbcd6d0c459552074918a50a795360692680b57347a8d1136bd96f9da962c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/604cbcd6d0c459552074918a50a795360692680b57347a8d1136bd96f9da962c?s=96&d=mm&r=g","caption":"Concello"},"url":"https:\/\/www.aguarda.es\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts\/1990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/comments?post=1990"}],"version-history":[{"count":0,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts\/1990\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/media\/1989"}],"wp:attachment":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/media?parent=1990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/categories?post=1990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/tags?post=1990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}