{"id":2272,"date":"2016-10-19T15:24:15","date_gmt":"2016-10-19T15:24:15","guid":{"rendered":"https:\/\/www.aguarda.es\/?p=2272"},"modified":"2016-10-19T15:24:15","modified_gmt":"2016-10-19T15:24:15","slug":"o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda","status":"publish","type":"post","link":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\/","title":{"rendered":"O Concello da Guarda e a Deputaci\u00f3n de Pontevedra anuncian a redacci\u00f3n dunha proposta de mobilidade para A Guarda"},"content":{"rendered":"<p dir=\"ltr\"><span><span>Despois de que o Concello da Guarda presentara diante da Deputaci\u00f3n de Pontevedra unha proposta para a humanizaci\u00f3n da r\u00faa Concepci\u00f3n Arenal e de manter varias reuni\u00f3ns en relaci\u00f3n a esta obra, a Deputaci\u00f3n propuxo ao goberno guard\u00e9s a integraci\u00f3n desta humanizaci\u00f3n nunha proposta de mobilidade sostible global para todo o Concello.<\/span><\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p dir=\"ltr\"><span>Despois de que o Concello da Guarda presentara diante da Deputaci\u00f3n de Pontevedra \u00a0unha proposta para a humanizaci\u00f3n da r\u00faa Concepci\u00f3n Arenal e de manter varias reuni\u00f3ns en relaci\u00f3n a esta obra, a Deputaci\u00f3n propuxo ao goberno guard\u00e9s a integraci\u00f3n desta humanizaci\u00f3n nunha proposta de mobilidade sostible global para todo o Concello. Iniciativa que contou coa inmediata aprobaci\u00f3n do o equipo de goberno Guard\u00e9s.<\/span><\/p>\n<p><span><span><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-2270\" src=\"https:\/\/www.aguarda.es\/wp-content\/uploads\/2016\/10\/2016_plan%20mobilidade%206.JPG\" alt=\"\" width=\"581\" height=\"436\" \/><\/span><\/span><\/p>\n<p dir=\"ltr\"><span>A necesidade \u00a0de facer un estudo deriva da importancia desta r\u00faa no que respecta ao tr\u00e1nsito de persoas e veh\u00edculos dentro do Concello. A Deputaci\u00f3n \u00a0xustifica esta iniciativa tendo en conta tam\u00e9n que Concepci\u00f3n Arenal \u00e9 unha v\u00eda provincial dentro dun casco urbano e das que m\u00e1is tr\u00e1fico soporta entre as v\u00edas da Deputaci\u00f3n. <\/span><\/p>\n<p dir=\"ltr\"><span>Na proposta inicial que o alcalde da Guarda presentou na Deputaci\u00f3n para a humanizaci\u00f3n desta r\u00faa xa contemplaba dar preferencia aos pe\u00f3ns sobre os veh\u00edculos naqueles lugares que era posible, en concreto, a peonalizaci\u00f3n da Praza Avelino Vicente.<\/span><\/p>\n<p><span><span>\u00a0<\/span><\/span><\/p>\n<p dir=\"ltr\"><span>A reuni\u00f3n de hoxe tivo como obxectivo a presentaci\u00f3n diante dos grupos da corporaci\u00f3n do Concello da Guarda da redacci\u00f3n dun estudo de mobilidade sustentable no que, en palabras do deputado de mobilidade Ux\u00edo Ben\u00edtez, a r\u00faa Concepci\u00f3n Arenal ser\u00eda unha peza clave. Segundo o deputado, a filosof\u00eda da proposta \u00e9 que as r\u00faas estean pensadas para as persoas e de que \u00e9 necesario adaptar os espazos p\u00fablicos a criterios de accesibilidade. Para isto se buscar\u00e1, se \u00e9 posible, que a proposta que se faga sexa aprobada por unanimidade dos grupos e sen\u00f3n, polo menos, que haxa unha maior\u00eda de consenso para un proxecto clave para A Guarda no que t\u00f3dolos partidos poidan participar e aportar ideas.<\/span><\/p>\n<p><span><span><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-2271\" src=\"https:\/\/www.aguarda.es\/wp-content\/uploads\/2016\/10\/2016_plan%20mobilidade%203.JPG\" alt=\"\" width=\"576\" height=\"432\" \/><\/span><\/span><\/p>\n<p dir=\"ltr\"><span>Tam\u00e9n asistiron \u00e1 reuni\u00f3n os t\u00e9cnicos da empresa encargada de realizar este estudo. Comentaron que nesta primeira fase o traballo se organiza en d\u00faas li\u00f1as: un estudo de campo sobre o terreo, e un an\u00e1lise a trav\u00e9s da participaci\u00f3n de persoas e axentes sociais implicados. \u00a0<\/span><\/p>\n<p dir=\"ltr\"><span>Na li\u00f1a da participaci\u00f3n ademais de buscar o consenso coa poboaci\u00f3n crearase unha mesa de traballo cos grupos pol\u00edticos para sacar conclusi\u00f3ns e extraer propostas que podan cubrir as necesidades detectadas e que se transformen en obras concretas, como suceder\u00e1 a corto prazo na r\u00faa Concepci\u00f3n Arenal.<\/span><\/p>\n<p><span><span>\u00a0<\/span><\/span><\/p>\n<p dir=\"ltr\"><span>O alcalde da Guarda, Antonio Lomba Baz, quixo expresar que a intenci\u00f3n desta reuni\u00f3n era a de implicar a t\u00f3dolos grupos pol\u00edticos e que estes puideran transmitir as s\u00faas opini\u00f3ns, d\u00fabidas e suxesti\u00f3ns sobre a proposta nesta fase previa do estudo. Ademais, recalcou que dende o grupo de goberno te\u00f1en claro que existen unha serie de condicionantes, derivados das necesidades que plantea unha r\u00faa da importancia que ten a de Concepci\u00f3n Arenal (con parada de autob\u00fas, baixada ao Porto, aparcadoiro, etc&#8230;) \u00a0que se ter\u00e1n moi en conta. Subli\u00f1ou que o estudo e o traballo de campo que est\u00e1 realizando a empresa \u00e9 para detectar o que necesita A Guarda e buscar posibles respostas a estas necesidades.<\/span><\/p>\n<p><span><span>\u00a0<\/span><\/span><\/p>\n<p dir=\"ltr\"><span>Ademais, Miguel Espa\u00f1ol, concelleiro de V\u00edas e Obras do Concello da Guarda, comentou a necesidade de realizar obra f\u00edsica en prazos concretos. Unha afirmaci\u00f3n que contou co compromiso por parte dos representantes da Deputaci\u00f3n, que calculan un prazo de 2 ou 3 meses para redactar a proposta de mobilidade de cara a realizar as obras en Concepci\u00f3n Arenal o vindeiro ano.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despois de que o Concello da Guarda presentara diante da Deputaci\u00f3n de Pontevedra unha proposta para a humanizaci\u00f3n da r\u00faa Concepci\u00f3n Arenal e de manter varias reuni\u00f3ns en relaci\u00f3n a esta obra, a Deputaci\u00f3n propuxo ao goberno guard\u00e9s a integraci\u00f3n &hellip; <\/p>\n","protected":false},"author":1,"featured_media":2271,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[47],"tags":[],"class_list":["post-2272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novas-vias-e-obras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O Concello da Guarda e a Deputaci\u00f3n de Pontevedra anuncian a redacci\u00f3n dunha proposta de mobilidade para A Guarda - Concello da Guarda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O Concello da Guarda e a Deputaci\u00f3n de Pontevedra anuncian a redacci\u00f3n dunha proposta de mobilidade para A Guarda - Concello da Guarda\" \/>\n<meta property=\"og:description\" content=\"Despois de que o Concello da Guarda presentara diante da Deputaci\u00f3n de Pontevedra unha proposta para a humanizaci\u00f3n da r\u00faa Concepci\u00f3n Arenal e de manter varias reuni\u00f3ns en relaci\u00f3n a esta obra, a Deputaci\u00f3n propuxo ao goberno guard\u00e9s a integraci\u00f3n &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\/\" \/>\n<meta property=\"og:site_name\" content=\"Concello da Guarda\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ConcellodaGuarda\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-19T15:24:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aguarda.es\/wp-content\/uploads\/2016\/10\/2016_plan%20mobilidade%203.JPG\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Concello\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AGuarda_es\" \/>\n<meta name=\"twitter:site\" content=\"@AGuarda_es\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Concello\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\\\/\"},\"author\":{\"name\":\"Concello\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/ac30f4d74843174f0af56c730f74dd57\"},\"headline\":\"O Concello da Guarda e a Deputaci\u00f3n de Pontevedra anuncian a redacci\u00f3n dunha proposta de mobilidade para A Guarda\",\"datePublished\":\"2016-10-19T15:24:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\\\/\"},\"wordCount\":696,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/2016_plan mobilidade 3.JPG\",\"articleSection\":[\"V\u00edas e obras\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\\\/\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\\\/\",\"name\":\"O Concello da Guarda e a Deputaci\u00f3n de Pontevedra anuncian a redacci\u00f3n dunha proposta de mobilidade para A Guarda - Concello da Guarda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/2016_plan mobilidade 3.JPG\",\"datePublished\":\"2016-10-19T15:24:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/ac30f4d74843174f0af56c730f74dd57\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aguarda.es\\\/en\\\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/2016_plan mobilidade 3.JPG\",\"contentUrl\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/2016_plan mobilidade 3.JPG\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O Concello da Guarda e a Deputaci\u00f3n de Pontevedra anuncian a redacci\u00f3n dunha proposta de mobilidade para A Guarda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/\",\"name\":\"Concello da Guarda\",\"description\":\"P\u00e1xina web do concello da Guarda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/ac30f4d74843174f0af56c730f74dd57\",\"name\":\"Concello\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/604cbcd6d0c459552074918a50a795360692680b57347a8d1136bd96f9da962c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/604cbcd6d0c459552074918a50a795360692680b57347a8d1136bd96f9da962c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/604cbcd6d0c459552074918a50a795360692680b57347a8d1136bd96f9da962c?s=96&d=mm&r=g\",\"caption\":\"Concello\"},\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O Concello da Guarda e a Deputaci\u00f3n de Pontevedra anuncian a redacci\u00f3n dunha proposta de mobilidade para A Guarda - Concello da Guarda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\/","og_locale":"en_US","og_type":"article","og_title":"O Concello da Guarda e a Deputaci\u00f3n de Pontevedra anuncian a redacci\u00f3n dunha proposta de mobilidade para A Guarda - Concello da Guarda","og_description":"Despois de que o Concello da Guarda presentara diante da Deputaci\u00f3n de Pontevedra unha proposta para a humanizaci\u00f3n da r\u00faa Concepci\u00f3n Arenal e de manter varias reuni\u00f3ns en relaci\u00f3n a esta obra, a Deputaci\u00f3n propuxo ao goberno guard\u00e9s a integraci\u00f3n &hellip;","og_url":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\/","og_site_name":"Concello da Guarda","article_publisher":"https:\/\/www.facebook.com\/ConcellodaGuarda","article_published_time":"2016-10-19T15:24:15+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2016\/10\/2016_plan mobilidade 3.JPG","type":"image\/jpeg"}],"author":"Concello","twitter_card":"summary_large_image","twitter_creator":"@AGuarda_es","twitter_site":"@AGuarda_es","twitter_misc":{"Written by":"Concello","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\/#article","isPartOf":{"@id":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\/"},"author":{"name":"Concello","@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/ac30f4d74843174f0af56c730f74dd57"},"headline":"O Concello da Guarda e a Deputaci\u00f3n de Pontevedra anuncian a redacci\u00f3n dunha proposta de mobilidade para A Guarda","datePublished":"2016-10-19T15:24:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\/"},"wordCount":696,"commentCount":0,"image":{"@id":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2016\/10\/2016_plan mobilidade 3.JPG","articleSection":["V\u00edas e obras"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\/","url":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\/","name":"O Concello da Guarda e a Deputaci\u00f3n de Pontevedra anuncian a redacci\u00f3n dunha proposta de mobilidade para A Guarda - Concello da Guarda","isPartOf":{"@id":"https:\/\/www.aguarda.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\/#primaryimage"},"image":{"@id":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2016\/10\/2016_plan mobilidade 3.JPG","datePublished":"2016-10-19T15:24:15+00:00","author":{"@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/ac30f4d74843174f0af56c730f74dd57"},"breadcrumb":{"@id":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\/#primaryimage","url":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2016\/10\/2016_plan mobilidade 3.JPG","contentUrl":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2016\/10\/2016_plan mobilidade 3.JPG","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-e-a-deputacion-de-pontevedra-anuncian-a-redaccion-dunha-proposta-de-mobilidade-para-a-guarda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.aguarda.es\/en\/"},{"@type":"ListItem","position":2,"name":"O Concello da Guarda e a Deputaci\u00f3n de Pontevedra anuncian a redacci\u00f3n dunha proposta de mobilidade para A Guarda"}]},{"@type":"WebSite","@id":"https:\/\/www.aguarda.es\/en\/#website","url":"https:\/\/www.aguarda.es\/en\/","name":"Concello da Guarda","description":"P\u00e1xina web do concello da Guarda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aguarda.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/ac30f4d74843174f0af56c730f74dd57","name":"Concello","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/604cbcd6d0c459552074918a50a795360692680b57347a8d1136bd96f9da962c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/604cbcd6d0c459552074918a50a795360692680b57347a8d1136bd96f9da962c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/604cbcd6d0c459552074918a50a795360692680b57347a8d1136bd96f9da962c?s=96&d=mm&r=g","caption":"Concello"},"url":"https:\/\/www.aguarda.es\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts\/2272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/comments?post=2272"}],"version-history":[{"count":0,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts\/2272\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/media\/2271"}],"wp:attachment":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/media?parent=2272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/categories?post=2272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/tags?post=2272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}