{"id":23475,"date":"2021-03-23T13:26:58","date_gmt":"2021-03-23T13:26:58","guid":{"rendered":"https:\/\/www.aguarda.es\/?p=23475"},"modified":"2021-03-23T13:26:58","modified_gmt":"2021-03-23T13:26:58","slug":"a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion","status":"publish","type":"post","link":"https:\/\/www.aguarda.es\/en\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\/","title":{"rendered":"A r\u00faa do Calvario, en A Guarda, volve contar con pavimento de pedra gracias a unha achega de 122.000 euros da Deputaci\u00f3n"},"content":{"rendered":"<p><strong><em>Santos H\u00e9ctor: \u201cAgora hai un precioso pavimento de pedra, que mesmo conserva algunha das vellas lousas e que mellora moito a accesibilidade para a veci\u00f1anza\u201d<\/em><\/strong><\/p>\n<p><strong><em>Antonio Lomba: \u201cOgall\u00e1 alg\u00fan d\u00eda a Xunta de Galicia te\u00f1a un plan de financiaci\u00f3n municipal que ofreza uns fondos comparables ao Plan Concellos, respectando a autonom\u00eda municipal para decidir que obras se fan\u201d<\/em><\/strong><\/p>\n<p>O Concello de A Guarda d\u00e1 un novo paso a prol da calidade urbana e a posta en valor do seu patrimonio coas obras de urbanizaci\u00f3n da r\u00faa do Calvario, que ve\u00f1en de rematar despois dun investimento de 122.000 euros da Deputaci\u00f3n a trav\u00e9s do Plan Concellos. O deputado provincial de Cooperaci\u00f3n, Santos H\u00e9ctor, e o alcalde, Antonio Lomba, percorreron hoxe esta v\u00eda que une o centro hist\u00f3rico coa capela da Nosa Se\u00f1ora da Gu\u00eda e valoraron o resultado final. Estiveron acompa\u00f1ados da deputada Raquel Gir\u00e1ldez e os concelleiros Montserrat Magallanes e Miguel Espa\u00f1ol.<\/p>\n<p>Santos H\u00e9ctor amosou a s\u00faa satisfacci\u00f3n polos resultados desta actuaci\u00f3n \u201cfeita con criterios de m\u00e1xima calidade\u201d. \u201cAgora hai un pavimento de pedra en plataforma \u00fanica, que mesmo conserva algunhas das lousas que estaban en mellores condici\u00f3ns\u201d. Destacou a mellora na accesibilidade nunha v\u00eda que pasou a ter prioridade peonil. O deputado remarcou os valores patrimoniais da r\u00faa e do propio centro hist\u00f3rico de A Guarda, polo que animou ao concello a continuar nesta li\u00f1a. \u201cTodo isto non fai m\u00e1is que confirmar a flexibilidade do Plan Concellos, que permite a cada Corporaci\u00f3n destinalos fondos da Deputaci\u00f3n ao que crea que \u00e9 m\u00e1is necesario, como o patrimonio hist\u00f3rico, como sucede neste caso, ao natural ou \u00e1 mellora de calquera dos servizos municipais\u201d.<\/p>\n<p>Na mesma li\u00f1a, Antonio Lomba puxo en valor o Plan Concellos, \u201cque permite obras como esta e que achega cartos aos municipios respectando a autonom\u00eda municipal; ogall\u00e1 a Xunta te\u00f1a alg\u00fan d\u00eda un plan de financiaci\u00f3n municipal que ofreza uns fondos comparables ao Plan Concellos, respectando a autonom\u00eda municipal para decidir que obras se fan, investindo onde se precisa\u201d.<br \/>\nO alcalde explicou que tr\u00e1tase da segunda fase de obras nesta r\u00faa e que queda a\u00ednda un \u00faltimo tramo \u201cque xa temos en carteira, porque a veci\u00f1anza quedou moi satisfeita\u201d. Antonio Lomba lembrou que a r\u00faa do Calvario estaba asfaltada sobre o un vello pavimento de pedra \u201cporque alg\u00fan alcalde as\u00ed o decidiu, para que os coches pasaran m\u00e1is r\u00e1pido\u201d. Amosouse, por tanto, feliz de poder \u201crecuperar a nobreza do barrio de Ribadavila\u201d, onde, explicou, faise un V\u00eda Crucis ata a capela. Lomba destacou o acabado do novo empedrado, en plataforma \u00fanica, e, ao tempo, o acerto de deixar testemu\u00f1a \u201ccoas vellas pedras que se conservaron, do que foi esta r\u00faa con anterioridade, porque baixo o asfalto estaba agochado parte do noso patrimonio\u201d.<\/p>\n<p><strong>M\u00e1is de 300 metros<\/strong><br \/>\nAs obras abranguen un tramo de m\u00e1is de 300 metros e consistiron no empedrado do pavimento, eliminando o asfalto anterior e dando as\u00ed prioridade \u00e1s circulaci\u00f3ns peon\u00eds, mantendo o tr\u00e1fico s\u00f3 nunha direcci\u00f3n. Deste xeito d\u00e1se continuidade ao pavimento p\u00e9treo e contin\u00faase o tramo xa recuperado na primeira parte da r\u00faa. As obras inclu\u00edron, ademais da integraci\u00f3n no pavimento dalgunha das vellas lousas recuperadas, a canalizaci\u00f3n das augas pluviais a trav\u00e9s dunha canle central, nova rede de distribuci\u00f3n de auga aos domicilios, nova rede de saneamento, acometidas para o alumeado p\u00fablico e, finalmente, instalaci\u00f3n de bocas de incendios.<\/p>\n<p>A actuaci\u00f3n s\u00famase aos m\u00e1is de 10 mill\u00f3ns de euros investidos pola Deputaci\u00f3n en A Guarda dende o ano 2015. Este ano recibe m\u00e1is de 800.000 euros con cargo ao Plan Concellos para obras en servizos de competencia municipal. A Guarda tam\u00e9n obtivo financiamento para un gran proxecto a trav\u00e9s do Plan DepoRemse, o que lle permitiu acometer o redese\u00f1o das r\u00faas Vigo e Celta, cunha achega de 500.000 euros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santos H\u00e9ctor: \u201cAgora hai un precioso pavimento de pedra, que mesmo conserva algunha das vellas lousas e que mellora moito a accesibilidade para a veci\u00f1anza\u201d Antonio Lomba: \u201cOgall\u00e1 alg\u00fan d\u00eda a Xunta de Galicia te\u00f1a un plan de financiaci\u00f3n municipal &hellip; <\/p>\n","protected":false},"author":2,"featured_media":23476,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[33],"tags":[226,246,261,2340],"class_list":["post-23475","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novas-xerais","tag-a-guarda","tag-obras","tag-plan-concellos","tag-rua-calvario"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A r\u00faa do Calvario, en A Guarda, volve contar con pavimento de pedra gracias a unha achega de 122.000 euros da Deputaci\u00f3n - Concello da Guarda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aguarda.es\/en\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A r\u00faa do Calvario, en A Guarda, volve contar con pavimento de pedra gracias a unha achega de 122.000 euros da Deputaci\u00f3n - Concello da Guarda\" \/>\n<meta property=\"og:description\" content=\"Santos H\u00e9ctor: \u201cAgora hai un precioso pavimento de pedra, que mesmo conserva algunha das vellas lousas e que mellora moito a accesibilidade para a veci\u00f1anza\u201d Antonio Lomba: \u201cOgall\u00e1 alg\u00fan d\u00eda a Xunta de Galicia te\u00f1a un plan de financiaci\u00f3n municipal &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aguarda.es\/en\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Concello da Guarda\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ConcellodaGuarda\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-23T13:26:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aguarda.es\/wp-content\/uploads\/2021\/03\/A-GUARDA-5-HORIZONTAL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"prensa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AGuarda_es\" \/>\n<meta name=\"twitter:site\" content=\"@AGuarda_es\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"prensa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\\\/\"},\"author\":{\"name\":\"prensa\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/c463ca3006858ffb349d11179d044f21\"},\"headline\":\"A r\u00faa do Calvario, en A Guarda, volve contar con pavimento de pedra gracias a unha achega de 122.000 euros da Deputaci\u00f3n\",\"datePublished\":\"2021-03-23T13:26:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\\\/\"},\"wordCount\":721,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/A-GUARDA-5-HORIZONTAL.jpg\",\"keywords\":[\"A Guarda\",\"Obras\",\"Plan Concellos\",\"rua calvario\"],\"articleSection\":[\"Xerais\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\\\/\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\\\/\",\"name\":\"A r\u00faa do Calvario, en A Guarda, volve contar con pavimento de pedra gracias a unha achega de 122.000 euros da Deputaci\u00f3n - Concello da Guarda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/A-GUARDA-5-HORIZONTAL.jpg\",\"datePublished\":\"2021-03-23T13:26:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/c463ca3006858ffb349d11179d044f21\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/A-GUARDA-5-HORIZONTAL.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/A-GUARDA-5-HORIZONTAL.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A r\u00faa do Calvario, en A Guarda, volve contar con pavimento de pedra gracias a unha achega de 122.000 euros da Deputaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/\",\"name\":\"Concello da Guarda\",\"description\":\"P\u00e1xina web do concello da Guarda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/c463ca3006858ffb349d11179d044f21\",\"name\":\"prensa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g\",\"caption\":\"prensa\"},\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/author\\\/prensa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A r\u00faa do Calvario, en A Guarda, volve contar con pavimento de pedra gracias a unha achega de 122.000 euros da Deputaci\u00f3n - Concello da Guarda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aguarda.es\/en\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\/","og_locale":"en_US","og_type":"article","og_title":"A r\u00faa do Calvario, en A Guarda, volve contar con pavimento de pedra gracias a unha achega de 122.000 euros da Deputaci\u00f3n - Concello da Guarda","og_description":"Santos H\u00e9ctor: \u201cAgora hai un precioso pavimento de pedra, que mesmo conserva algunha das vellas lousas e que mellora moito a accesibilidade para a veci\u00f1anza\u201d Antonio Lomba: \u201cOgall\u00e1 alg\u00fan d\u00eda a Xunta de Galicia te\u00f1a un plan de financiaci\u00f3n municipal &hellip;","og_url":"https:\/\/www.aguarda.es\/en\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\/","og_site_name":"Concello da Guarda","article_publisher":"https:\/\/www.facebook.com\/ConcellodaGuarda","article_published_time":"2021-03-23T13:26:58+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2021\/03\/A-GUARDA-5-HORIZONTAL.jpg","type":"image\/jpeg"}],"author":"prensa","twitter_card":"summary_large_image","twitter_creator":"@AGuarda_es","twitter_site":"@AGuarda_es","twitter_misc":{"Written by":"prensa","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aguarda.es\/en\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\/#article","isPartOf":{"@id":"https:\/\/www.aguarda.es\/en\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\/"},"author":{"name":"prensa","@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/c463ca3006858ffb349d11179d044f21"},"headline":"A r\u00faa do Calvario, en A Guarda, volve contar con pavimento de pedra gracias a unha achega de 122.000 euros da Deputaci\u00f3n","datePublished":"2021-03-23T13:26:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aguarda.es\/en\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\/"},"wordCount":721,"commentCount":0,"image":{"@id":"https:\/\/www.aguarda.es\/en\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2021\/03\/A-GUARDA-5-HORIZONTAL.jpg","keywords":["A Guarda","Obras","Plan Concellos","rua calvario"],"articleSection":["Xerais"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.aguarda.es\/en\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\/","url":"https:\/\/www.aguarda.es\/en\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\/","name":"A r\u00faa do Calvario, en A Guarda, volve contar con pavimento de pedra gracias a unha achega de 122.000 euros da Deputaci\u00f3n - Concello da Guarda","isPartOf":{"@id":"https:\/\/www.aguarda.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aguarda.es\/en\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\/#primaryimage"},"image":{"@id":"https:\/\/www.aguarda.es\/en\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2021\/03\/A-GUARDA-5-HORIZONTAL.jpg","datePublished":"2021-03-23T13:26:58+00:00","author":{"@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/c463ca3006858ffb349d11179d044f21"},"breadcrumb":{"@id":"https:\/\/www.aguarda.es\/en\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aguarda.es\/en\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.aguarda.es\/en\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\/#primaryimage","url":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2021\/03\/A-GUARDA-5-HORIZONTAL.jpg","contentUrl":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2021\/03\/A-GUARDA-5-HORIZONTAL.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.aguarda.es\/en\/a-rua-do-calvario-en-a-guarda-volve-contar-con-pavimento-de-pedra-gracias-a-unha-achega-de-122-000-euros-da-deputacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.aguarda.es\/en\/"},{"@type":"ListItem","position":2,"name":"A r\u00faa do Calvario, en A Guarda, volve contar con pavimento de pedra gracias a unha achega de 122.000 euros da Deputaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.aguarda.es\/en\/#website","url":"https:\/\/www.aguarda.es\/en\/","name":"Concello da Guarda","description":"P\u00e1xina web do concello da Guarda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aguarda.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/c463ca3006858ffb349d11179d044f21","name":"prensa","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g","caption":"prensa"},"url":"https:\/\/www.aguarda.es\/en\/author\/prensa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts\/23475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/comments?post=23475"}],"version-history":[{"count":1,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts\/23475\/revisions"}],"predecessor-version":[{"id":23478,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts\/23475\/revisions\/23478"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/media\/23476"}],"wp:attachment":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/media?parent=23475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/categories?post=23475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/tags?post=23475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}