{"id":2390,"date":"2016-12-07T09:19:49","date_gmt":"2016-12-07T09:19:49","guid":{"rendered":"https:\/\/www.aguarda.es\/?p=2390"},"modified":"2016-12-07T09:19:49","modified_gmt":"2016-12-07T09:19:49","slug":"a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro","status":"publish","type":"post","link":"https:\/\/www.aguarda.es\/en\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\/","title":{"rendered":"A exposici\u00f3n \u201cImaxes con fondo\u201d estar\u00e1 na Casa do Concello do 5 ao 23 de decembro"},"content":{"rendered":"<p lang=\"gl-ES\"><span>Dende o luns 5 de decembro xa se pode visitar, nas d\u00faas plantas da Casa do Concello da Guarda a exposici\u00f3n \u201cImaxes con fondo\u201d, organizada polo Fondo Galego de Cooperaci\u00f3n en colaboraci\u00f3n co concello da Guarda.<\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p lang=\"gl-ES\"><span><span>Dende o luns 5 de decembro xa se pode visitar, nas d\u00faas plantas da Casa do Concello da Guarda a exposici\u00f3n \u201cImaxes con fondo\u201d, organizada polo Fondo Galego de Cooperaci\u00f3n en colaboraci\u00f3n co concello da Guarda.<\/span><\/span><\/p>\n<p lang=\"gl-ES\"><span>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-2388\" src=\"https:\/\/www.aguarda.es\/wp-content\/uploads\/2016\/12\/2016_expo%20imaxes%20con%20Fondo%202.JPG\" alt=\"\" width=\"488\" height=\"366\" \/><\/span><\/p>\n<p lang=\"gl-ES\"><span>O Fondo Galego de Cooperaci\u00f3n e Solidariedade \u00e9 unha rede integrada por 88 concellos e as deputaci\u00f3ns da Coru\u00f1a e Lugo que concentra os seus esforzos no eido da cooperaci\u00f3n ao desenvolvemento. Nesta mostra de fotograf\u00eda, dese\u00f1ada polo debuxante Pepe Carreiro, incl\u00faense as 19 obras que concorreron no concurso de fotograf\u00eda \u201cImaxes con fondo\u201d e que buscan concienciar sobre as condutas respectuosas coa contorna e coas persoas que nela habitan. Os temas das fotograf\u00edas que se poden ver na mostra abarcan diversos temas como a<span lang=\"gl-ES\"> solidariedade interxeneracional, o aforro enerx\u00e9tico, a protecci\u00f3n ambiental, o consumismo, a prostituci\u00f3n, a explotaci\u00f3n laboral, a crise alimentaria ou as desigualdades Norte -Sur.<\/span><\/span><\/p>\n<p lang=\"gl-ES\"><span>\u00a0<\/span><\/p>\n<p lang=\"gl-ES\"><span>Este concurso celebrou este ano a s\u00faa terceira edici\u00f3n, Imaxes con Fondo III <span lang=\"gl-ES\">e no <\/span><a href=\"https:\/\/premium.easypromosapp.com\/p\/612509?lc=glg\"><span>Facebook<\/span><\/a><span lang=\"gl-ES\"> do Fondo Galego est\u00e1 aberta a votaci\u00f3n para elixir entre as imaxes participantes, que nesta segunda edici\u00f3n versan sobre o tema da interculturalidade.<\/span><\/span><\/p>\n<p lang=\"gl-ES\"><span>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-2389\" src=\"https:\/\/www.aguarda.es\/wp-content\/uploads\/2016\/12\/2016_expo%20imaxes%20con%20Fondo%204.JPG\" alt=\"\" width=\"486\" height=\"365\" \/><\/span><\/p>\n<p lang=\"gl-ES\"><span>Dende o concello da Guarda se anima a todos os veci\u00f1os e veci\u00f1as \u00e1 achegarse \u00e1 Casa Consistorial en horario de 8 a 15 horas, de luns a venres, para poder contemplar unha mostra que combina o arte da fotograf\u00eda coa sensibilizaci\u00f3n e, que ten como obxectivo principal a promoci\u00f3n da reflexi\u00f3n, o pensamento cr\u00edtico e un cambio de actitude dentro da nosa sociedade por medio da palabra e a imaxe.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dende o luns 5 de decembro xa se pode visitar, nas d\u00faas plantas da Casa do Concello da Guarda a exposici\u00f3n \u201cImaxes con fondo\u201d, organizada polo Fondo Galego de Cooperaci\u00f3n en colaboraci\u00f3n co concello da Guarda.<\/p>\n","protected":false},"author":1,"featured_media":2389,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[48],"tags":[],"class_list":["post-2390","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novas-xuventude"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A exposici\u00f3n \u201cImaxes con fondo\u201d estar\u00e1 na Casa do Concello do 5 ao 23 de decembro - Concello da Guarda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aguarda.es\/en\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A exposici\u00f3n \u201cImaxes con fondo\u201d estar\u00e1 na Casa do Concello do 5 ao 23 de decembro - Concello da Guarda\" \/>\n<meta property=\"og:description\" content=\"Dende o luns 5 de decembro xa se pode visitar, nas d\u00faas plantas da Casa do Concello da Guarda a exposici\u00f3n \u201cImaxes con fondo\u201d, organizada polo Fondo Galego de Cooperaci\u00f3n en colaboraci\u00f3n co concello da Guarda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aguarda.es\/en\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\/\" \/>\n<meta property=\"og:site_name\" content=\"Concello da Guarda\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ConcellodaGuarda\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-07T09:19:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aguarda.es\/wp-content\/uploads\/2016\/12\/2016_expo%20imaxes%20con%20Fondo%204.JPG\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Concello\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AGuarda_es\" \/>\n<meta name=\"twitter:site\" content=\"@AGuarda_es\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Concello\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\\\/\"},\"author\":{\"name\":\"Concello\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/ac30f4d74843174f0af56c730f74dd57\"},\"headline\":\"A exposici\u00f3n \u201cImaxes con fondo\u201d estar\u00e1 na Casa do Concello do 5 ao 23 de decembro\",\"datePublished\":\"2016-12-07T09:19:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\\\/\"},\"wordCount\":328,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/2016_expo imaxes con Fondo 4.JPG\",\"articleSection\":[\"Xuventude\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\\\/\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\\\/\",\"name\":\"A exposici\u00f3n \u201cImaxes con fondo\u201d estar\u00e1 na Casa do Concello do 5 ao 23 de decembro - Concello da Guarda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/2016_expo imaxes con Fondo 4.JPG\",\"datePublished\":\"2016-12-07T09:19:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/ac30f4d74843174f0af56c730f74dd57\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/2016_expo imaxes con Fondo 4.JPG\",\"contentUrl\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/2016_expo imaxes con Fondo 4.JPG\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A exposici\u00f3n \u201cImaxes con fondo\u201d estar\u00e1 na Casa do Concello do 5 ao 23 de decembro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/\",\"name\":\"Concello da Guarda\",\"description\":\"P\u00e1xina web do concello da Guarda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/ac30f4d74843174f0af56c730f74dd57\",\"name\":\"Concello\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/604cbcd6d0c459552074918a50a795360692680b57347a8d1136bd96f9da962c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/604cbcd6d0c459552074918a50a795360692680b57347a8d1136bd96f9da962c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/604cbcd6d0c459552074918a50a795360692680b57347a8d1136bd96f9da962c?s=96&d=mm&r=g\",\"caption\":\"Concello\"},\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A exposici\u00f3n \u201cImaxes con fondo\u201d estar\u00e1 na Casa do Concello do 5 ao 23 de decembro - Concello da Guarda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aguarda.es\/en\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\/","og_locale":"en_US","og_type":"article","og_title":"A exposici\u00f3n \u201cImaxes con fondo\u201d estar\u00e1 na Casa do Concello do 5 ao 23 de decembro - Concello da Guarda","og_description":"Dende o luns 5 de decembro xa se pode visitar, nas d\u00faas plantas da Casa do Concello da Guarda a exposici\u00f3n \u201cImaxes con fondo\u201d, organizada polo Fondo Galego de Cooperaci\u00f3n en colaboraci\u00f3n co concello da Guarda.","og_url":"https:\/\/www.aguarda.es\/en\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\/","og_site_name":"Concello da Guarda","article_publisher":"https:\/\/www.facebook.com\/ConcellodaGuarda","article_published_time":"2016-12-07T09:19:49+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2016\/12\/2016_expo imaxes con Fondo 4.JPG","type":"image\/jpeg"}],"author":"Concello","twitter_card":"summary_large_image","twitter_creator":"@AGuarda_es","twitter_site":"@AGuarda_es","twitter_misc":{"Written by":"Concello","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aguarda.es\/en\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\/#article","isPartOf":{"@id":"https:\/\/www.aguarda.es\/en\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\/"},"author":{"name":"Concello","@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/ac30f4d74843174f0af56c730f74dd57"},"headline":"A exposici\u00f3n \u201cImaxes con fondo\u201d estar\u00e1 na Casa do Concello do 5 ao 23 de decembro","datePublished":"2016-12-07T09:19:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aguarda.es\/en\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\/"},"wordCount":328,"commentCount":0,"image":{"@id":"https:\/\/www.aguarda.es\/en\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2016\/12\/2016_expo imaxes con Fondo 4.JPG","articleSection":["Xuventude"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.aguarda.es\/en\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\/","url":"https:\/\/www.aguarda.es\/en\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\/","name":"A exposici\u00f3n \u201cImaxes con fondo\u201d estar\u00e1 na Casa do Concello do 5 ao 23 de decembro - Concello da Guarda","isPartOf":{"@id":"https:\/\/www.aguarda.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aguarda.es\/en\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\/#primaryimage"},"image":{"@id":"https:\/\/www.aguarda.es\/en\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2016\/12\/2016_expo imaxes con Fondo 4.JPG","datePublished":"2016-12-07T09:19:49+00:00","author":{"@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/ac30f4d74843174f0af56c730f74dd57"},"breadcrumb":{"@id":"https:\/\/www.aguarda.es\/en\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aguarda.es\/en\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.aguarda.es\/en\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\/#primaryimage","url":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2016\/12\/2016_expo imaxes con Fondo 4.JPG","contentUrl":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2016\/12\/2016_expo imaxes con Fondo 4.JPG","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.aguarda.es\/en\/a-exposicion-imaxes-con-fondo-estara-na-casa-do-concello-do-5-ao-23-de-decembro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.aguarda.es\/en\/"},{"@type":"ListItem","position":2,"name":"A exposici\u00f3n \u201cImaxes con fondo\u201d estar\u00e1 na Casa do Concello do 5 ao 23 de decembro"}]},{"@type":"WebSite","@id":"https:\/\/www.aguarda.es\/en\/#website","url":"https:\/\/www.aguarda.es\/en\/","name":"Concello da Guarda","description":"P\u00e1xina web do concello da Guarda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aguarda.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/ac30f4d74843174f0af56c730f74dd57","name":"Concello","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/604cbcd6d0c459552074918a50a795360692680b57347a8d1136bd96f9da962c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/604cbcd6d0c459552074918a50a795360692680b57347a8d1136bd96f9da962c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/604cbcd6d0c459552074918a50a795360692680b57347a8d1136bd96f9da962c?s=96&d=mm&r=g","caption":"Concello"},"url":"https:\/\/www.aguarda.es\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts\/2390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/comments?post=2390"}],"version-history":[{"count":0,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts\/2390\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/media\/2389"}],"wp:attachment":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/media?parent=2390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/categories?post=2390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/tags?post=2390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}