{"id":24056,"date":"2021-07-08T11:29:38","date_gmt":"2021-07-08T11:29:38","guid":{"rendered":"https:\/\/www.aguarda.es\/?p=24056"},"modified":"2021-07-08T11:38:21","modified_gmt":"2021-07-08T11:38:21","slug":"o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano","status":"publish","type":"post","link":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\/","title":{"rendered":"O concello da Guarda incrementa un 50% o n\u00famero de prazas no campamento urbano"},"content":{"rendered":"<p>O alcalde da Guarda, Antonio Lomba e a Concelleira de Educaci\u00f3n e formaci\u00f3n, F\u00e1tima Rodr\u00edguez, acompa\u00f1aron \u00e1s familias no inicio do campamento urbano que se desenvolver\u00e1 nos colexios de Solanas, Sinde e no recinto do Centro de Interpretaci\u00f3n do Castelo de Sta Cruz.<\/p>\n<p>Este ano o equipo de goberno da Guarda considerou que era unha prioridade atender as necesidades das familias guardesas en relaci\u00f3n coa necesaria conciliaci\u00f3n entre a vida familiar e laboral durante a \u00e9poca de ver\u00e1n. Para iso decidiu utilizar recursos procedentes de actividades que non estaban programadas, coma a Festa da Langosta, e acordou adicar eses recursos en aumentar o n\u00famero de prazas do campamento urbano, pasando de 40 no ano 2019 \u00e1s 60 deste 2021, sendo un incremento do 50 % respecto de anos anteriores.<\/p>\n<p>Pero non s\u00f3 decidiu aumentar o n\u00famero de prazas sen\u00f3n que se aumentou tam\u00e9n o per\u00edodo que os nen@s pod\u00edan permanecer no campamento, permitindo chegar a un m\u00e1ximo de 60 d\u00edas.<\/p>\n<p>Isto \u00e9 froito da consideraci\u00f3n que o equipo de goberno tivo en relaci\u00f3n coas necesidades amosadas polas familias guardesas \u00e1 hora de poder conciliar a vida familiar e laboral no per\u00edodo estival. A ningu\u00e9n se lle escapa que nestes momentos de pandemia \u00e9 moito m\u00e1is dif\u00edcil esta conciliaci\u00f3n ao non poder contar as familias coa axuda dos familiares que en anos anteriores cubr\u00eda esta necesidade. Se considerou que o concello deb\u00eda atender esta problem\u00e1tica e adicar recursos municipais no campamento urbano, habilit\u00e1ronse deste xeito tres espazos diferenciados para poder establecer grupos burbulla sen contacto entre eles como criterio de prevenci\u00f3n de calquera tipo de contaxio. Como xa informou o alcalde da Guarda, Antonio Lomba, a Xunta de Galicia non lle concedeu ao concello da Guarda a subvenci\u00f3n por conciliaci\u00f3n, o que implica que temos que afrontar este servizo con recursos propios.<\/p>\n<p>Ademais persoal municipal adicou tempo e esforzo para sacar adiante unha contrataci\u00f3n nun tempo reducido, tempo e persoal que poder\u00eda estar adicado \u00e1 contrataci\u00f3n doutros servizos, pero que o alcalde e concelleiros do equipo de goberno prefiren adicar a xestionar e solucionar os problemas reais da cidadan\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O alcalde da Guarda, Antonio Lomba e a Concelleira de Educaci\u00f3n e formaci\u00f3n, F\u00e1tima Rodr\u00edguez, acompa\u00f1aron \u00e1s familias no inicio do campamento urbano que se desenvolver\u00e1 nos colexios de Solanas, Sinde e no recinto do Centro de Interpretaci\u00f3n do Castelo &hellip; <\/p>\n","protected":false},"author":2,"featured_media":24057,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[33],"tags":[226,374],"class_list":["post-24056","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novas-xerais","tag-a-guarda","tag-campamento-urbano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O concello da Guarda incrementa un 50% o n\u00famero de prazas no campamento urbano - Concello da Guarda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O concello da Guarda incrementa un 50% o n\u00famero de prazas no campamento urbano - Concello da Guarda\" \/>\n<meta property=\"og:description\" content=\"O alcalde da Guarda, Antonio Lomba e a Concelleira de Educaci\u00f3n e formaci\u00f3n, F\u00e1tima Rodr\u00edguez, acompa\u00f1aron \u00e1s familias no inicio do campamento urbano que se desenvolver\u00e1 nos colexios de Solanas, Sinde e no recinto do Centro de Interpretaci\u00f3n do Castelo &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\/\" \/>\n<meta property=\"og:site_name\" content=\"Concello da Guarda\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ConcellodaGuarda\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-08T11:29:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-08T11:38:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aguarda.es\/wp-content\/uploads\/2021\/07\/Sin-t\u00edtulo-1-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"prensa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AGuarda_es\" \/>\n<meta name=\"twitter:site\" content=\"@AGuarda_es\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"prensa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\\\/\"},\"author\":{\"name\":\"prensa\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/c463ca3006858ffb349d11179d044f21\"},\"headline\":\"O concello da Guarda incrementa un 50% o n\u00famero de prazas no campamento urbano\",\"datePublished\":\"2021-07-08T11:29:38+00:00\",\"dateModified\":\"2021-07-08T11:38:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\\\/\"},\"wordCount\":387,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Sin-t\u00edtulo-1-2.jpg\",\"keywords\":[\"A Guarda\",\"Campamento urbano\"],\"articleSection\":[\"Xerais\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\\\/\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\\\/\",\"name\":\"O concello da Guarda incrementa un 50% o n\u00famero de prazas no campamento urbano - Concello da Guarda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Sin-t\u00edtulo-1-2.jpg\",\"datePublished\":\"2021-07-08T11:29:38+00:00\",\"dateModified\":\"2021-07-08T11:38:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/c463ca3006858ffb349d11179d044f21\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aguarda.es\\\/en\\\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Sin-t\u00edtulo-1-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aguarda.es\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Sin-t\u00edtulo-1-2.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O concello da Guarda incrementa un 50% o n\u00famero de prazas no campamento urbano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/\",\"name\":\"Concello da Guarda\",\"description\":\"P\u00e1xina web do concello da Guarda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/#\\\/schema\\\/person\\\/c463ca3006858ffb349d11179d044f21\",\"name\":\"prensa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g\",\"caption\":\"prensa\"},\"url\":\"https:\\\/\\\/www.aguarda.es\\\/en\\\/author\\\/prensa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O concello da Guarda incrementa un 50% o n\u00famero de prazas no campamento urbano - Concello da Guarda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\/","og_locale":"en_US","og_type":"article","og_title":"O concello da Guarda incrementa un 50% o n\u00famero de prazas no campamento urbano - Concello da Guarda","og_description":"O alcalde da Guarda, Antonio Lomba e a Concelleira de Educaci\u00f3n e formaci\u00f3n, F\u00e1tima Rodr\u00edguez, acompa\u00f1aron \u00e1s familias no inicio do campamento urbano que se desenvolver\u00e1 nos colexios de Solanas, Sinde e no recinto do Centro de Interpretaci\u00f3n do Castelo &hellip;","og_url":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\/","og_site_name":"Concello da Guarda","article_publisher":"https:\/\/www.facebook.com\/ConcellodaGuarda","article_published_time":"2021-07-08T11:29:38+00:00","article_modified_time":"2021-07-08T11:38:21+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2021\/07\/Sin-t\u00edtulo-1-2.jpg","type":"image\/jpeg"}],"author":"prensa","twitter_card":"summary_large_image","twitter_creator":"@AGuarda_es","twitter_site":"@AGuarda_es","twitter_misc":{"Written by":"prensa","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\/#article","isPartOf":{"@id":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\/"},"author":{"name":"prensa","@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/c463ca3006858ffb349d11179d044f21"},"headline":"O concello da Guarda incrementa un 50% o n\u00famero de prazas no campamento urbano","datePublished":"2021-07-08T11:29:38+00:00","dateModified":"2021-07-08T11:38:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\/"},"wordCount":387,"commentCount":0,"image":{"@id":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2021\/07\/Sin-t\u00edtulo-1-2.jpg","keywords":["A Guarda","Campamento urbano"],"articleSection":["Xerais"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\/","url":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\/","name":"O concello da Guarda incrementa un 50% o n\u00famero de prazas no campamento urbano - Concello da Guarda","isPartOf":{"@id":"https:\/\/www.aguarda.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\/#primaryimage"},"image":{"@id":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2021\/07\/Sin-t\u00edtulo-1-2.jpg","datePublished":"2021-07-08T11:29:38+00:00","dateModified":"2021-07-08T11:38:21+00:00","author":{"@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/c463ca3006858ffb349d11179d044f21"},"breadcrumb":{"@id":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\/#primaryimage","url":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2021\/07\/Sin-t\u00edtulo-1-2.jpg","contentUrl":"https:\/\/www.aguarda.es\/wp-content\/uploads\/2021\/07\/Sin-t\u00edtulo-1-2.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.aguarda.es\/en\/o-concello-da-guarda-incrementa-un-50-o-numero-de-prazas-no-campamento-urbano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.aguarda.es\/en\/"},{"@type":"ListItem","position":2,"name":"O concello da Guarda incrementa un 50% o n\u00famero de prazas no campamento urbano"}]},{"@type":"WebSite","@id":"https:\/\/www.aguarda.es\/en\/#website","url":"https:\/\/www.aguarda.es\/en\/","name":"Concello da Guarda","description":"P\u00e1xina web do concello da Guarda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aguarda.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.aguarda.es\/en\/#\/schema\/person\/c463ca3006858ffb349d11179d044f21","name":"prensa","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/387e117f874ba5d0a3439060b45d914395d77287b2e4890a49d1599fc3ef9189?s=96&d=mm&r=g","caption":"prensa"},"url":"https:\/\/www.aguarda.es\/en\/author\/prensa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts\/24056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/comments?post=24056"}],"version-history":[{"count":3,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts\/24056\/revisions"}],"predecessor-version":[{"id":24061,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/posts\/24056\/revisions\/24061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/media\/24057"}],"wp:attachment":[{"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/media?parent=24056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/categories?post=24056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aguarda.es\/en\/wp-json\/wp\/v2\/tags?post=24056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}